{"id":3721,"date":"2024-06-29T08:00:36","date_gmt":"2024-06-29T08:00:36","guid":{"rendered":"https:\/\/www.motointegrator.pt\/blog\/\/?p=3721"},"modified":"2025-11-25T13:04:39","modified_gmt":"2025-11-25T13:04:39","slug":"conversao-de-travoes-de-tambor-em-travoes-de-disco","status":"publish","type":"post","link":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/","title":{"rendered":"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco &#8211; guia"},"content":{"rendered":"A fiabilidade dos <a href=\"\/produtos\/sistema-de-travagem-114\/\">trav\u00f5es<\/a> \u00e9 essencial para a seguran\u00e7a rodovi\u00e1ria dos ve\u00edculos a motor. A quest\u00e3o de saber se os trav\u00f5es de tambor ou os trav\u00f5es de disco s\u00e3o a melhor escolha para o tr\u00e1fego rodovi\u00e1rio tem sido objeto de um aceso debate durante anos.\r\n<h2>Os trav\u00f5es de tambor s\u00e3o a &#8220;base&#8221; da tecnologia de travagem autom\u00f3vel<\/h2>\r\nPor volta de 1900, os conhecidos pioneiros do sector autom\u00f3vel Louis Renault e Wilhelm Maybach lan\u00e7aram as bases dos actuais trav\u00f5es de tambor. Para tal, Louis Renault simplesmente deslocou as <a href=\"\/produtos\/maxilas-de-travao-1140201\/\">maxilas de trav\u00e3o<\/a> (que anteriormente se encontravam no exterior) para um tambor. Isto protegeu os cal\u00e7os de trav\u00e3o de influ\u00eancias externas e permitiu-lhes otimizar o seu efeito de travagem. At\u00e9 hoje, os trav\u00f5es de tambor continuam a ser utilizados em ve\u00edculos numa forma mais desenvolvida. Um trav\u00e3o de tambor moderno \u00e9 composto por um tambor de trav\u00e3o que est\u00e1 firmemente ligado \u00e0 roda e segue as rota\u00e7\u00f5es da roda.\r\n\r\nAt\u00e9 ao final dos anos 70, <a href=\"\/produtos\/travoes-de-tambor-11402\/\">os trav\u00f5es de tambor<\/a> continuavam a ser a norma na maioria dos ve\u00edculos. No entanto, surgiram cada vez mais problemas com acidentes em ve\u00edculos com uma grande cilindrada. Em muitos casos, os trav\u00f5es de tambor eram inadequados em termos de design e tamb\u00e9m completamente subdimensionados em rela\u00e7\u00e3o \u00e0 capacidade do motor. Para resolver os problemas, cada vez mais fabricantes de ve\u00edculos mudaram para trav\u00f5es de disco nos anos seguintes.\r\n\r\nAtualmente, s\u00e3o utilizados tanto trav\u00f5es de tambor como trav\u00f5es de disco e os especialistas debatem calorosamente qual \u00e9 o melhor sistema de travagem. Os trav\u00f5es de disco s\u00e3o geralmente utilizados nas rodas dianteiras, uma vez que oferecem um desempenho de travagem perfeitamente uniforme em qualquer situa\u00e7\u00e3o de condu\u00e7\u00e3o. No entanto, muitos fabricantes de ve\u00edculos continuam a utilizar trav\u00f5es de tambor nas rodas traseiras. Na maioria dos casos, isto \u00e9 feito por raz\u00f5es de custo, uma vez que os trav\u00f5es podem ser combinados de forma f\u00e1cil e barata com um trav\u00e3o de estacionamento (trav\u00e3o de m\u00e3o).\r\n\r\n<figure id=\"attachment_16565\" aria-describedby=\"caption-attachment-16565\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-16565 size-full\" src=\"https:\/\/www.motointegrator.pt\/blog\/wp-content\/uploads\/sites\/17\/2024\/06\/travagem.jpg\" alt=\"\" width=\"500\" height=\"334\" srcset=\"https:\/\/www.motointegrator.pt\/blog\/wp-content\/uploads\/sites\/17\/2024\/06\/travagem.jpg 500w, https:\/\/www.motointegrator.pt\/blog\/wp-content\/uploads\/sites\/17\/2024\/06\/travagem-300x200.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><figcaption id=\"caption-attachment-16565\" class=\"wp-caption-text\">\u00a9 Shutterstock \/ The Five Aggregates<\/figcaption><\/figure>\r\n<h2>Trav\u00e3o de tambor &#8211; estrutura e fun\u00e7\u00e3o<\/h2>\r\nUm trav\u00e3o de tambor \u00e9 constitu\u00eddo principalmente por um tambor rotativo. No seu interior, existem 2 cal\u00e7os de trav\u00e3o firmemente fixados. Assim que acionar os trav\u00f5es do seu ve\u00edculo, os dois cal\u00e7os de trav\u00e3o s\u00e3o pressionados firmemente contra o interior do tambor. Isto cria uma forte fric\u00e7\u00e3o e a roda p\u00e1ra lentamente. Quando se solta o pedal do trav\u00e3o, molas especiais asseguram que as duas maxilas de trav\u00e3o regressam \u00e0 sua posi\u00e7\u00e3o original. Para al\u00e9m dos cl\u00e1ssicos trav\u00f5es de tambor simplex, os trav\u00f5es de tambor duplex especiais j\u00e1 se estabeleceram no mercado. Nesta variante popular, cada <a href=\"\/produtos\/maxilas-de-travao-1140201\/\">cal\u00e7o de trav\u00e3o<\/a> tem o seu pr\u00f3prio dispositivo de acionamento lateral. Como resultado, os dois cal\u00e7os de trav\u00e3o est\u00e3o em overrun e refor\u00e7am-se um ao outro automaticamente.\r\n\r\nEm compara\u00e7\u00e3o direta com os trav\u00f5es simplex, o efeito de travagem \u00e9 cerca de 50 por cento superior. No entanto, devido ao processo de produ\u00e7\u00e3o dispendioso e ao maior esfor\u00e7o de manuten\u00e7\u00e3o envolvido, muitos fabricantes ainda confiam nos favor\u00e1veis trav\u00f5es de tambor simplex.\r\n<h2>Trav\u00e3o de disco &#8211; conce\u00e7\u00e3o e funcionamento<\/h2>\r\nO <a href=\"\/produtos\/travoes-de-disco-11401\/\">trav\u00e3o de disco<\/a> \u00e9 composto por um <a href=\"\/produtos\/discos-de-travao-1140103\/\">disco de trav\u00e3o<\/a>, que est\u00e1 ligado ao <a href=\"\/produtos\/cubos-de-roda-11522\/\">cubo da roda<\/a>, e por um suporte de trav\u00e3o. A pin\u00e7a de trav\u00e3o (pin\u00e7a de trav\u00e3o) est\u00e1 ligada a este suporte. A pin\u00e7a engloba todo o disco de trav\u00e3o e cont\u00e9m os cal\u00e7os de trav\u00e3o e os pist\u00f5es de trav\u00e3o. Estes \u00faltimos pressionam as pastilhas de trav\u00e3o diretamente contra o disco de trav\u00e3o na dire\u00e7\u00e3o axial.\r\n\r\nO disco de trav\u00e3o \u00e9 normalmente fixado diretamente a um cubo de roda, mas em alguns modelos pode tamb\u00e9m ser fixado ao diferencial. Um trav\u00e3o de disco \u00e9 utilizado apenas para travar e, por isso, o material utilizado tpode ser concebido de forma \u00f3ptima para os respectivos requisitos de travagem. O di\u00e2metro do disco de trav\u00e3o determina em grande parte o torque de travagem e o desempenho da travagem. Nos ve\u00edculos de alto desempenho, o di\u00e2metro da roda limita o di\u00e2metro interior m\u00e1ximo das jantes e, por conseguinte, tamb\u00e9m o di\u00e2metro do disco de trav\u00e3o. S\u00e3o utilizadas as jantes mais largas poss\u00edveis para que os discos possam ser t\u00e3o grandes quanto poss\u00edvel.\r\n<h2>Compara\u00e7\u00e3o entre trav\u00f5es de tambor e trav\u00f5es de disco &#8211; vantagens e desvantagens<\/h2>\r\nO trav\u00e3o de tambor n\u00e3o consegue dissipar de forma fi\u00e1vel o calor de fric\u00e7\u00e3o gerado. Por esta raz\u00e3o, pode ocorrer um sobreaquecimento no tambor, especialmente durante a travagem de emerg\u00eancia ou em processos de travagem mais longos a altas velocidades. A acumula\u00e7\u00e3o de calor resultante reduz significativamente a for\u00e7a de fric\u00e7\u00e3o entre as maxilas do trav\u00e3o e a parede interior do tambor. Como resultado, o trav\u00e3o de tambor perde cerca de 50 a 100 por cento do seu efeito de travagem.\r\n\r\nOutro problema \u00e9 que o sistema encapsulado \u00e9 muito dif\u00edcil de monitorizar a partir do exterior. Isto significa que ningu\u00e9m pode dizer exatamente o que est\u00e1 a acontecer no interior do trav\u00e3o. Estar\u00e1 um cilindro a verter ou uma das duas maxilas de trav\u00e3o a desintegrar-se? Ser\u00e1 que uma mola de retorno se partiu ou o trav\u00e3o est\u00e1 a sufocar na sua pr\u00f3pria abras\u00e3o? S\u00f3 \u00e9 poss\u00edvel responder a todas estas quest\u00f5es importantes retirando a roda do ve\u00edculo e abrindo o tambor do trav\u00e3o.\r\n\r\n<div class=\"product-slider\" style=\"--swiper-theme-color: #d80812;--swiper-navigation-size: 22px;--swiper-navigation-sides-offset: -25px;\"><div class=\"slider-title\"><svg id=\"fi_9219671\" enable-background=\"new 0 0 64 64\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g><g><path d=\"m25.308 61.679c-3.514 0-6.373-2.859-6.373-6.373s2.859-6.372 6.373-6.372 6.373 2.858 6.373 6.372-2.859 6.373-6.373 6.373zm0-8.745c-1.308 0-2.373 1.064-2.373 2.372 0 1.309 1.064 2.373 2.373 2.373s2.373-1.064 2.373-2.373c0-1.308-1.064-2.372-2.373-2.372z\"><\/path><path d=\"m47.462 61.679c-3.514 0-6.372-2.859-6.372-6.373s2.858-6.372 6.372-6.372 6.373 2.858 6.373 6.372-2.86 6.373-6.373 6.373zm0-8.745c-1.308 0-2.372 1.064-2.372 2.372 0 1.309 1.064 2.373 2.372 2.373 1.309 0 2.373-1.064 2.373-2.373 0-1.308-1.065-2.372-2.373-2.372z\"><\/path><\/g><path d=\"m52.128 43.994h-31.419c-3.057 0-5.668-2.081-6.35-5.061l-6.521-28.477c-.086-.376-.346-.698-.696-.86l-5.409-2.507c-1.252-.58-1.797-2.066-1.217-3.319.58-1.252 2.067-1.797 3.319-1.217l5.409 2.507c1.743.807 3.04 2.407 3.468 4.28l6.521 28.479c.158.692.765 1.176 1.476 1.176h31.419c.708 0 1.314-.481 1.476-1.171l5.07-21.813c.145-.62-.119-1.071-.288-1.284-.17-.214-.55-.572-1.186-.572h-37c-1.381 0-2.5-1.119-2.5-2.5s1.119-2.5 2.5-2.5h37c1.999 0 3.857.897 5.101 2.462s1.696 3.579 1.244 5.526l-5.071 21.814c-.691 2.965-3.3 5.037-6.346 5.037z\"><\/path><\/g><\/svg><h2>Compre pe\u00e7as para o sistema de travagem do seu carro online.<\/h2><\/div><div class=\"swiper\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide product\"><img decoding=\"async\" src=\"https:\/\/ic-files-res.cloudinary.com\/image\/upload\/t_pad_white1200x1200v1\/v1\/item\/nmuobkbgpv5wbcpyv36s.jpg\" alt=\"18253\" \/><a class=\"line-clamp-title\" href=\"https:\/\/www.motointegrator.pt\/produto\/390231-sensor-do-abs-dianteirotraseiro-esquerdodireito-wabco-441-032-921-2\" target=\"_blank\">Sensor do ABS, dianteiro\/traseiro, esquerdo\/direito  WABCO 441 032 921 2<\/a><p>Wabco<\/p><div class=\"price-container\"><p class=\"price\">27.83 EUR<\/p><button class=\"price-button\"><svg id=\"fi_9219671\" enable-background=\"new 0 0 64 64\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g><g><path d=\"m25.308 61.679c-3.514 0-6.373-2.859-6.373-6.373s2.859-6.372 6.373-6.372 6.373 2.858 6.373 6.372-2.859 6.373-6.373 6.373zm0-8.745c-1.308 0-2.373 1.064-2.373 2.372 0 1.309 1.064 2.373 2.373 2.373s2.373-1.064 2.373-2.373c0-1.308-1.064-2.372-2.373-2.372z\"><\/path><path d=\"m47.462 61.679c-3.514 0-6.372-2.859-6.372-6.373s2.858-6.372 6.372-6.372 6.373 2.858 6.373 6.372-2.86 6.373-6.373 6.373zm0-8.745c-1.308 0-2.372 1.064-2.372 2.372 0 1.309 1.064 2.373 2.372 2.373 1.309 0 2.373-1.064 2.373-2.373 0-1.308-1.065-2.372-2.373-2.372z\"><\/path><\/g><path d=\"m52.128 43.994h-31.419c-3.057 0-5.668-2.081-6.35-5.061l-6.521-28.477c-.086-.376-.346-.698-.696-.86l-5.409-2.507c-1.252-.58-1.797-2.066-1.217-3.319.58-1.252 2.067-1.797 3.319-1.217l5.409 2.507c1.743.807 3.04 2.407 3.468 4.28l6.521 28.479c.158.692.765 1.176 1.476 1.176h31.419c.708 0 1.314-.481 1.476-1.171l5.07-21.813c.145-.62-.119-1.071-.288-1.284-.17-.214-.55-.572-1.186-.572h-37c-1.381 0-2.5-1.119-2.5-2.5s1.119-2.5 2.5-2.5h37c1.999 0 3.857.897 5.101 2.462s1.696 3.579 1.244 5.526l-5.071 21.814c-.691 2.965-3.3 5.037-6.346 5.037z\"><\/path><\/g><\/svg><path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m8.25 4.5 7.5 7.5-7.5 7.5\" \/><\/svg><\/button><\/div><p class=\"price-info\">Inclui IVA, sem portes de envio<\/p><\/div><div class=\"swiper-slide product\"><img decoding=\"async\" src=\"https:\/\/ic-files-res.cloudinary.com\/image\/upload\/t_pad_white1200x1200v1\/v1\/item\/jlroxg2pzbcd2upmbx5k.jpg\" alt=\"18268\" \/><a class=\"line-clamp-title\" href=\"https:\/\/www.motointegrator.pt\/produto\/391767-filtro-do-secador-de-ar-wabco-432-901-223-2\" target=\"_blank\">Filtro do secador de ar WABCO 432 901 223 2<\/a><p>Wabco<\/p><div class=\"price-container\"><p class=\"price\">39.76 EUR<\/p><button class=\"price-button\"><svg id=\"fi_9219671\" enable-background=\"new 0 0 64 64\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g><g><path d=\"m25.308 61.679c-3.514 0-6.373-2.859-6.373-6.373s2.859-6.372 6.373-6.372 6.373 2.858 6.373 6.372-2.859 6.373-6.373 6.373zm0-8.745c-1.308 0-2.373 1.064-2.373 2.372 0 1.309 1.064 2.373 2.373 2.373s2.373-1.064 2.373-2.373c0-1.308-1.064-2.372-2.373-2.372z\"><\/path><path d=\"m47.462 61.679c-3.514 0-6.372-2.859-6.372-6.373s2.858-6.372 6.372-6.372 6.373 2.858 6.373 6.372-2.86 6.373-6.373 6.373zm0-8.745c-1.308 0-2.372 1.064-2.372 2.372 0 1.309 1.064 2.373 2.372 2.373 1.309 0 2.373-1.064 2.373-2.373 0-1.308-1.065-2.372-2.373-2.372z\"><\/path><\/g><path d=\"m52.128 43.994h-31.419c-3.057 0-5.668-2.081-6.35-5.061l-6.521-28.477c-.086-.376-.346-.698-.696-.86l-5.409-2.507c-1.252-.58-1.797-2.066-1.217-3.319.58-1.252 2.067-1.797 3.319-1.217l5.409 2.507c1.743.807 3.04 2.407 3.468 4.28l6.521 28.479c.158.692.765 1.176 1.476 1.176h31.419c.708 0 1.314-.481 1.476-1.171l5.07-21.813c.145-.62-.119-1.071-.288-1.284-.17-.214-.55-.572-1.186-.572h-37c-1.381 0-2.5-1.119-2.5-2.5s1.119-2.5 2.5-2.5h37c1.999 0 3.857.897 5.101 2.462s1.696 3.579 1.244 5.526l-5.071 21.814c-.691 2.965-3.3 5.037-6.346 5.037z\"><\/path><\/g><\/svg><path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m8.25 4.5 7.5 7.5-7.5 7.5\" \/><\/svg><\/button><\/div><p class=\"price-info\">Inclui IVA, sem portes de envio<\/p><\/div><div class=\"swiper-slide product\"><img decoding=\"async\" src=\"https:\/\/ic-files-res.cloudinary.com\/image\/upload\/t_pad_white1200x1200v1\/v1\/item\/ltnkrpthu4em68kqdtyq.jpg\" alt=\"18238\" \/><a class=\"line-clamp-title\" href=\"https:\/\/www.motointegrator.pt\/produto\/391956-diafragma-cilindro-do-travao-de-diafragma-wabco-8971205164\" target=\"_blank\">Diafragma, cilindro do trav\u00e3o de diafragma WABCO 8971205164<\/a><p>Wabco<\/p><div class=\"price-container\"><p class=\"price\">23.09 EUR<\/p><button class=\"price-button\"><svg id=\"fi_9219671\" enable-background=\"new 0 0 64 64\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g><g><path d=\"m25.308 61.679c-3.514 0-6.373-2.859-6.373-6.373s2.859-6.372 6.373-6.372 6.373 2.858 6.373 6.372-2.859 6.373-6.373 6.373zm0-8.745c-1.308 0-2.373 1.064-2.373 2.372 0 1.309 1.064 2.373 2.373 2.373s2.373-1.064 2.373-2.373c0-1.308-1.064-2.372-2.373-2.372z\"><\/path><path d=\"m47.462 61.679c-3.514 0-6.372-2.859-6.372-6.373s2.858-6.372 6.372-6.372 6.373 2.858 6.373 6.372-2.86 6.373-6.373 6.373zm0-8.745c-1.308 0-2.372 1.064-2.372 2.372 0 1.309 1.064 2.373 2.372 2.373 1.309 0 2.373-1.064 2.373-2.373 0-1.308-1.065-2.372-2.373-2.372z\"><\/path><\/g><path d=\"m52.128 43.994h-31.419c-3.057 0-5.668-2.081-6.35-5.061l-6.521-28.477c-.086-.376-.346-.698-.696-.86l-5.409-2.507c-1.252-.58-1.797-2.066-1.217-3.319.58-1.252 2.067-1.797 3.319-1.217l5.409 2.507c1.743.807 3.04 2.407 3.468 4.28l6.521 28.479c.158.692.765 1.176 1.476 1.176h31.419c.708 0 1.314-.481 1.476-1.171l5.07-21.813c.145-.62-.119-1.071-.288-1.284-.17-.214-.55-.572-1.186-.572h-37c-1.381 0-2.5-1.119-2.5-2.5s1.119-2.5 2.5-2.5h37c1.999 0 3.857.897 5.101 2.462s1.696 3.579 1.244 5.526l-5.071 21.814c-.691 2.965-3.3 5.037-6.346 5.037z\"><\/path><\/g><\/svg><path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m8.25 4.5 7.5 7.5-7.5 7.5\" \/><\/svg><\/button><\/div><p class=\"price-info\">Inclui IVA, sem portes de envio<\/p><\/div><div class=\"swiper-slide product\"><img decoding=\"async\" src=\"https:\/\/ic-files-res.cloudinary.com\/image\/upload\/t_pad_white1200x1200v1\/v1\/item\/penfwhweiawajzcvq6nb.jpg\" alt=\"18214\" \/><a class=\"line-clamp-title\" href=\"https:\/\/www.motointegrator.pt\/produto\/385337-conjunto-de-pastilhas-de-travao-trw-gdb5067\" target=\"_blank\">Conjunto de pastilhas de trav\u00e3o TRW GDB5067<\/a><p>Trw<\/p><div class=\"price-container\"><p class=\"price\">67.56 EUR<\/p><button class=\"price-button\"><svg id=\"fi_9219671\" enable-background=\"new 0 0 64 64\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g><g><path d=\"m25.308 61.679c-3.514 0-6.373-2.859-6.373-6.373s2.859-6.372 6.373-6.372 6.373 2.858 6.373 6.372-2.859 6.373-6.373 6.373zm0-8.745c-1.308 0-2.373 1.064-2.373 2.372 0 1.309 1.064 2.373 2.373 2.373s2.373-1.064 2.373-2.373c0-1.308-1.064-2.372-2.373-2.372z\"><\/path><path d=\"m47.462 61.679c-3.514 0-6.372-2.859-6.372-6.373s2.858-6.372 6.372-6.372 6.373 2.858 6.373 6.372-2.86 6.373-6.373 6.373zm0-8.745c-1.308 0-2.372 1.064-2.372 2.372 0 1.309 1.064 2.373 2.372 2.373 1.309 0 2.373-1.064 2.373-2.373 0-1.308-1.065-2.372-2.373-2.372z\"><\/path><\/g><path d=\"m52.128 43.994h-31.419c-3.057 0-5.668-2.081-6.35-5.061l-6.521-28.477c-.086-.376-.346-.698-.696-.86l-5.409-2.507c-1.252-.58-1.797-2.066-1.217-3.319.58-1.252 2.067-1.797 3.319-1.217l5.409 2.507c1.743.807 3.04 2.407 3.468 4.28l6.521 28.479c.158.692.765 1.176 1.476 1.176h31.419c.708 0 1.314-.481 1.476-1.171l5.07-21.813c.145-.62-.119-1.071-.288-1.284-.17-.214-.55-.572-1.186-.572h-37c-1.381 0-2.5-1.119-2.5-2.5s1.119-2.5 2.5-2.5h37c1.999 0 3.857.897 5.101 2.462s1.696 3.579 1.244 5.526l-5.071 21.814c-.691 2.965-3.3 5.037-6.346 5.037z\"><\/path><\/g><\/svg><path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m8.25 4.5 7.5 7.5-7.5 7.5\" \/><\/svg><\/button><\/div><p class=\"price-info\">Inclui IVA, sem portes de envio<\/p><\/div><div class=\"swiper-slide product\"><img decoding=\"async\" src=\"https:\/\/ic-files-res.cloudinary.com\/image\/upload\/t_pad_white1200x1200v1\/v1\/item\/ido8ipnbgmqvv27tucla.jpg\" alt=\"18264\" \/><a class=\"line-clamp-title\" href=\"https:\/\/www.motointegrator.pt\/produto\/390630-conjunto-de-pastilhas-de-travao-sbp-07-p29108\" target=\"_blank\">Conjunto de pastilhas de trav\u00e3o SBP 07-P29108<\/a><p>Sbp<\/p><div class=\"price-container\"><p class=\"price\">56.35 EUR<\/p><button class=\"price-button\"><svg id=\"fi_9219671\" enable-background=\"new 0 0 64 64\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g><g><path d=\"m25.308 61.679c-3.514 0-6.373-2.859-6.373-6.373s2.859-6.372 6.373-6.372 6.373 2.858 6.373 6.372-2.859 6.373-6.373 6.373zm0-8.745c-1.308 0-2.373 1.064-2.373 2.372 0 1.309 1.064 2.373 2.373 2.373s2.373-1.064 2.373-2.373c0-1.308-1.064-2.372-2.373-2.372z\"><\/path><path d=\"m47.462 61.679c-3.514 0-6.372-2.859-6.372-6.373s2.858-6.372 6.372-6.372 6.373 2.858 6.373 6.372-2.86 6.373-6.373 6.373zm0-8.745c-1.308 0-2.372 1.064-2.372 2.372 0 1.309 1.064 2.373 2.372 2.373 1.309 0 2.373-1.064 2.373-2.373 0-1.308-1.065-2.372-2.373-2.372z\"><\/path><\/g><path d=\"m52.128 43.994h-31.419c-3.057 0-5.668-2.081-6.35-5.061l-6.521-28.477c-.086-.376-.346-.698-.696-.86l-5.409-2.507c-1.252-.58-1.797-2.066-1.217-3.319.58-1.252 2.067-1.797 3.319-1.217l5.409 2.507c1.743.807 3.04 2.407 3.468 4.28l6.521 28.479c.158.692.765 1.176 1.476 1.176h31.419c.708 0 1.314-.481 1.476-1.171l5.07-21.813c.145-.62-.119-1.071-.288-1.284-.17-.214-.55-.572-1.186-.572h-37c-1.381 0-2.5-1.119-2.5-2.5s1.119-2.5 2.5-2.5h37c1.999 0 3.857.897 5.101 2.462s1.696 3.579 1.244 5.526l-5.071 21.814c-.691 2.965-3.3 5.037-6.346 5.037z\"><\/path><\/g><\/svg><path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m8.25 4.5 7.5 7.5-7.5 7.5\" \/><\/svg><\/button><\/div><p class=\"price-info\">Inclui IVA, sem portes de envio<\/p><\/div><div class=\"swiper-slide product\"><img decoding=\"async\" src=\"https:\/\/ic-files-res.cloudinary.com\/image\/upload\/t_pad_white1200x1200v1\/v1\/item\/jgjrpgcbfatk0kpavyh9.jpg\" alt=\"18456\" \/><a class=\"line-clamp-title\" href=\"https:\/\/www.motointegrator.pt\/produto\/365479-conjunto-de-pastilhas-de-travao-textar-2927801\" target=\"_blank\">Conjunto de pastilhas de trav\u00e3o TEXTAR 2927801<\/a><p>Textar<\/p><div class=\"price-container\"><p class=\"price\">107.26 EUR<\/p><button class=\"price-button\"><svg id=\"fi_9219671\" enable-background=\"new 0 0 64 64\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g><g><path d=\"m25.308 61.679c-3.514 0-6.373-2.859-6.373-6.373s2.859-6.372 6.373-6.372 6.373 2.858 6.373 6.372-2.859 6.373-6.373 6.373zm0-8.745c-1.308 0-2.373 1.064-2.373 2.372 0 1.309 1.064 2.373 2.373 2.373s2.373-1.064 2.373-2.373c0-1.308-1.064-2.372-2.373-2.372z\"><\/path><path d=\"m47.462 61.679c-3.514 0-6.372-2.859-6.372-6.373s2.858-6.372 6.372-6.372 6.373 2.858 6.373 6.372-2.86 6.373-6.373 6.373zm0-8.745c-1.308 0-2.372 1.064-2.372 2.372 0 1.309 1.064 2.373 2.372 2.373 1.309 0 2.373-1.064 2.373-2.373 0-1.308-1.065-2.372-2.373-2.372z\"><\/path><\/g><path d=\"m52.128 43.994h-31.419c-3.057 0-5.668-2.081-6.35-5.061l-6.521-28.477c-.086-.376-.346-.698-.696-.86l-5.409-2.507c-1.252-.58-1.797-2.066-1.217-3.319.58-1.252 2.067-1.797 3.319-1.217l5.409 2.507c1.743.807 3.04 2.407 3.468 4.28l6.521 28.479c.158.692.765 1.176 1.476 1.176h31.419c.708 0 1.314-.481 1.476-1.171l5.07-21.813c.145-.62-.119-1.071-.288-1.284-.17-.214-.55-.572-1.186-.572h-37c-1.381 0-2.5-1.119-2.5-2.5s1.119-2.5 2.5-2.5h37c1.999 0 3.857.897 5.101 2.462s1.696 3.579 1.244 5.526l-5.071 21.814c-.691 2.965-3.3 5.037-6.346 5.037z\"><\/path><\/g><\/svg><path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m8.25 4.5 7.5 7.5-7.5 7.5\" \/><\/svg><\/button><\/div><p class=\"price-info\">Inclui IVA, sem portes de envio<\/p><\/div><div class=\"swiper-slide product\"><img decoding=\"async\" src=\"https:\/\/ic-files-res.cloudinary.com\/image\/upload\/t_pad_white1200x1200v1\/v1\/item\/n3hek9fr5exf0nk1m9tx.jpg\" alt=\"18466\" \/><a class=\"line-clamp-title\" href=\"https:\/\/www.motointegrator.pt\/produto\/333676-conectores-linha-de-ar-comprimido-raufoss-623-7695\" target=\"_blank\">Conectores, linha de ar comprimido RAUFOSS 623 7695<\/a><p>Raufoss<\/p><div class=\"price-container\"><p class=\"price\">18.61 EUR<\/p><button class=\"price-button\"><svg id=\"fi_9219671\" enable-background=\"new 0 0 64 64\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g><g><path d=\"m25.308 61.679c-3.514 0-6.373-2.859-6.373-6.373s2.859-6.372 6.373-6.372 6.373 2.858 6.373 6.372-2.859 6.373-6.373 6.373zm0-8.745c-1.308 0-2.373 1.064-2.373 2.372 0 1.309 1.064 2.373 2.373 2.373s2.373-1.064 2.373-2.373c0-1.308-1.064-2.372-2.373-2.372z\"><\/path><path d=\"m47.462 61.679c-3.514 0-6.372-2.859-6.372-6.373s2.858-6.372 6.372-6.372 6.373 2.858 6.373 6.372-2.86 6.373-6.373 6.373zm0-8.745c-1.308 0-2.372 1.064-2.372 2.372 0 1.309 1.064 2.373 2.372 2.373 1.309 0 2.373-1.064 2.373-2.373 0-1.308-1.065-2.372-2.373-2.372z\"><\/path><\/g><path d=\"m52.128 43.994h-31.419c-3.057 0-5.668-2.081-6.35-5.061l-6.521-28.477c-.086-.376-.346-.698-.696-.86l-5.409-2.507c-1.252-.58-1.797-2.066-1.217-3.319.58-1.252 2.067-1.797 3.319-1.217l5.409 2.507c1.743.807 3.04 2.407 3.468 4.28l6.521 28.479c.158.692.765 1.176 1.476 1.176h31.419c.708 0 1.314-.481 1.476-1.171l5.07-21.813c.145-.62-.119-1.071-.288-1.284-.17-.214-.55-.572-1.186-.572h-37c-1.381 0-2.5-1.119-2.5-2.5s1.119-2.5 2.5-2.5h37c1.999 0 3.857.897 5.101 2.462s1.696 3.579 1.244 5.526l-5.071 21.814c-.691 2.965-3.3 5.037-6.346 5.037z\"><\/path><\/g><\/svg><path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m8.25 4.5 7.5 7.5-7.5 7.5\" \/><\/svg><\/button><\/div><p class=\"price-info\">Inclui IVA, sem portes de envio<\/p><\/div><div class=\"swiper-slide product\"><img decoding=\"async\" src=\"https:\/\/ic-files-res.cloudinary.com\/image\/upload\/t_pad_white1200x1200v1\/v1\/item\/tfknfnpw3teearelwf1l.jpg\" alt=\"18106\" \/><a class=\"line-clamp-title\" href=\"https:\/\/www.motointegrator.pt\/produto\/373710-valvula-de-travao-reboque-pneumatics-pn-10136\" target=\"_blank\">V\u00e1lvula de trav\u00e3o, reboque PNEUMATICS PN-10136<\/a><p>Pneumatics<\/p><div class=\"price-container\"><p class=\"price\">43.94 EUR<\/p><button class=\"price-button\"><svg id=\"fi_9219671\" enable-background=\"new 0 0 64 64\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g><g><path d=\"m25.308 61.679c-3.514 0-6.373-2.859-6.373-6.373s2.859-6.372 6.373-6.372 6.373 2.858 6.373 6.372-2.859 6.373-6.373 6.373zm0-8.745c-1.308 0-2.373 1.064-2.373 2.372 0 1.309 1.064 2.373 2.373 2.373s2.373-1.064 2.373-2.373c0-1.308-1.064-2.372-2.373-2.372z\"><\/path><path d=\"m47.462 61.679c-3.514 0-6.372-2.859-6.372-6.373s2.858-6.372 6.372-6.372 6.373 2.858 6.373 6.372-2.86 6.373-6.373 6.373zm0-8.745c-1.308 0-2.372 1.064-2.372 2.372 0 1.309 1.064 2.373 2.372 2.373 1.309 0 2.373-1.064 2.373-2.373 0-1.308-1.065-2.372-2.373-2.372z\"><\/path><\/g><path d=\"m52.128 43.994h-31.419c-3.057 0-5.668-2.081-6.35-5.061l-6.521-28.477c-.086-.376-.346-.698-.696-.86l-5.409-2.507c-1.252-.58-1.797-2.066-1.217-3.319.58-1.252 2.067-1.797 3.319-1.217l5.409 2.507c1.743.807 3.04 2.407 3.468 4.28l6.521 28.479c.158.692.765 1.176 1.476 1.176h31.419c.708 0 1.314-.481 1.476-1.171l5.07-21.813c.145-.62-.119-1.071-.288-1.284-.17-.214-.55-.572-1.186-.572h-37c-1.381 0-2.5-1.119-2.5-2.5s1.119-2.5 2.5-2.5h37c1.999 0 3.857.897 5.101 2.462s1.696 3.579 1.244 5.526l-5.071 21.814c-.691 2.965-3.3 5.037-6.346 5.037z\"><\/path><\/g><\/svg><path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m8.25 4.5 7.5 7.5-7.5 7.5\" \/><\/svg><\/button><\/div><p class=\"price-info\">Inclui IVA, sem portes de envio<\/p><\/div><div class=\"swiper-slide product\"><img decoding=\"async\" src=\"https:\/\/ic-files-res.cloudinary.com\/image\/upload\/t_pad_white1200x1200v1\/v1\/item\/mska21f5wx4rqitih99a.jpg\" alt=\"33169\" \/><a class=\"line-clamp-title\" href=\"https:\/\/www.motointegrator.pt\/produto\/715925-filtro-de-secador-de-ar-separador-de-oleo-mahle-al-24\" target=\"_blank\">Filtro de secador de ar, separador de \u00f3leo MAHLE AL 24<\/a><p>Mahle<\/p><div class=\"price-container\"><p class=\"price\">19.41 EUR<\/p><button class=\"price-button\"><svg id=\"fi_9219671\" enable-background=\"new 0 0 64 64\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g><g><path d=\"m25.308 61.679c-3.514 0-6.373-2.859-6.373-6.373s2.859-6.372 6.373-6.372 6.373 2.858 6.373 6.372-2.859 6.373-6.373 6.373zm0-8.745c-1.308 0-2.373 1.064-2.373 2.372 0 1.309 1.064 2.373 2.373 2.373s2.373-1.064 2.373-2.373c0-1.308-1.064-2.372-2.373-2.372z\"><\/path><path d=\"m47.462 61.679c-3.514 0-6.372-2.859-6.372-6.373s2.858-6.372 6.372-6.372 6.373 2.858 6.373 6.372-2.86 6.373-6.373 6.373zm0-8.745c-1.308 0-2.372 1.064-2.372 2.372 0 1.309 1.064 2.373 2.372 2.373 1.309 0 2.373-1.064 2.373-2.373 0-1.308-1.065-2.372-2.373-2.372z\"><\/path><\/g><path d=\"m52.128 43.994h-31.419c-3.057 0-5.668-2.081-6.35-5.061l-6.521-28.477c-.086-.376-.346-.698-.696-.86l-5.409-2.507c-1.252-.58-1.797-2.066-1.217-3.319.58-1.252 2.067-1.797 3.319-1.217l5.409 2.507c1.743.807 3.04 2.407 3.468 4.28l6.521 28.479c.158.692.765 1.176 1.476 1.176h31.419c.708 0 1.314-.481 1.476-1.171l5.07-21.813c.145-.62-.119-1.071-.288-1.284-.17-.214-.55-.572-1.186-.572h-37c-1.381 0-2.5-1.119-2.5-2.5s1.119-2.5 2.5-2.5h37c1.999 0 3.857.897 5.101 2.462s1.696 3.579 1.244 5.526l-5.071 21.814c-.691 2.965-3.3 5.037-6.346 5.037z\"><\/path><\/g><\/svg><path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m8.25 4.5 7.5 7.5-7.5 7.5\" \/><\/svg><\/button><\/div><p class=\"price-info\">Inclui IVA, sem portes de envio<\/p><\/div><div class=\"swiper-slide product\"><img decoding=\"async\" src=\"https:\/\/ic-files-res.cloudinary.com\/image\/upload\/t_pad_white1200x1200v1\/v1\/item\/dwcytpaafg1jlyhyas2n.jpg\" alt=\"18229\" \/><a class=\"line-clamp-title\" href=\"https:\/\/www.motointegrator.pt\/produto\/389292-unidade-hidraulica-abs-wabco-472-195-016-0\" target=\"_blank\">Unidade hidr\u00e1ulica, ABS WABCO 472 195 016 0<\/a><p>Wabco<\/p><div class=\"price-container\"><p class=\"price\">47.18 EUR<\/p><button class=\"price-button\"><svg id=\"fi_9219671\" enable-background=\"new 0 0 64 64\" height=\"512\" viewBox=\"0 0 64 64\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g><g><path d=\"m25.308 61.679c-3.514 0-6.373-2.859-6.373-6.373s2.859-6.372 6.373-6.372 6.373 2.858 6.373 6.372-2.859 6.373-6.373 6.373zm0-8.745c-1.308 0-2.373 1.064-2.373 2.372 0 1.309 1.064 2.373 2.373 2.373s2.373-1.064 2.373-2.373c0-1.308-1.064-2.372-2.373-2.372z\"><\/path><path d=\"m47.462 61.679c-3.514 0-6.372-2.859-6.372-6.373s2.858-6.372 6.372-6.372 6.373 2.858 6.373 6.372-2.86 6.373-6.373 6.373zm0-8.745c-1.308 0-2.372 1.064-2.372 2.372 0 1.309 1.064 2.373 2.372 2.373 1.309 0 2.373-1.064 2.373-2.373 0-1.308-1.065-2.372-2.373-2.372z\"><\/path><\/g><path d=\"m52.128 43.994h-31.419c-3.057 0-5.668-2.081-6.35-5.061l-6.521-28.477c-.086-.376-.346-.698-.696-.86l-5.409-2.507c-1.252-.58-1.797-2.066-1.217-3.319.58-1.252 2.067-1.797 3.319-1.217l5.409 2.507c1.743.807 3.04 2.407 3.468 4.28l6.521 28.479c.158.692.765 1.176 1.476 1.176h31.419c.708 0 1.314-.481 1.476-1.171l5.07-21.813c.145-.62-.119-1.071-.288-1.284-.17-.214-.55-.572-1.186-.572h-37c-1.381 0-2.5-1.119-2.5-2.5s1.119-2.5 2.5-2.5h37c1.999 0 3.857.897 5.101 2.462s1.696 3.579 1.244 5.526l-5.071 21.814c-.691 2.965-3.3 5.037-6.346 5.037z\"><\/path><\/g><\/svg><path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"m8.25 4.5 7.5 7.5-7.5 7.5\" \/><\/svg><\/button><\/div><p class=\"price-info\">Inclui IVA, sem portes de envio<\/p><\/div><\/div><div class=\"swiper-pagination\"><\/div><div class=\"swiper-button-prev\"><\/div><div class=\"swiper-button-next\"><\/div><\/div><\/div>\r\n<h3>Trav\u00f5es de tambor &#8211; vantagens<\/h3>\r\nApesar destes dois grandes problemas e desvantagens, os trav\u00f5es de tambor continuam a ser populares porque s\u00e3o mais baratos do que os trav\u00f5es de disco.\r\n\r\nEm compara\u00e7\u00e3o com o trav\u00e3o de tambor, o <a href=\"\/produtos\/travoes-de-disco-11401\/\">trav\u00e3o de disco<\/a> tem uma tecnologia significativamente superior e oferece v\u00e1rias vantagens. Pode absorver for\u00e7as de travagem muito mais fortes sem sobreaquecer. O trav\u00e3o arrefece e limpa-se automaticamente. Se o trav\u00e3o de disco se desgastar ou tiver um defeito, pode reconhec\u00ea-lo imediatamente e n\u00e3o tem de retirar primeiro a roda. Em termos de conce\u00e7\u00e3o e constru\u00e7\u00e3o, os trav\u00f5es de disco s\u00e3o mais complexos e mais pesados do que os trav\u00f5es de tambor. Al\u00e9m disso, os trav\u00f5es de disco s\u00e3o mais sens\u00edveis e n\u00e3o est\u00e3o t\u00e3o bem protegidos contra influ\u00eancias abrasivas, como a \u00e1gua e o sal da estrada.\r\n\r\nO resultado final \u00e9 que um trav\u00e3o de disco custa muito mais dinheiro do que um trav\u00e3o de tambor. Esta \u00e9 tamb\u00e9m a principal raz\u00e3o pela qual a convers\u00e3o dos trav\u00f5es de tambor para os modernos trav\u00f5es de disco s\u00f3 foi efectuada passo a passo.\r\n<h2>Faz sentido mudar para trav\u00f5es de disco?<\/h2>\r\nDurante quase 25 anos, a maioria dos ve\u00edculos utilizou uma combina\u00e7\u00e3o de trav\u00f5es de disco e trav\u00f5es de tambor. Desde meados da d\u00e9cada de 1990, cada vez mais ve\u00edculos de gama m\u00e9dia e alguns autom\u00f3veis pequenos foram completamente convertidos para trav\u00f5es de disco. Os modelos e marcas orientados para o desporto mantiveram os ultrapassados trav\u00f5es de tambor durante muito mais tempo. Embora o trav\u00e3o de tambor seja, sem d\u00favida, uma pe\u00e7a ultrapassada da tecnologia autom\u00f3vel, uma mudan\u00e7a ou convers\u00e3o s\u00f3 faz sentido em alguns casos. O sistema de travagem de cada ve\u00edculo \u00e9 optimizado para as respectivas caracter\u00edsticas do ve\u00edculo. Por exemplo, Se o seu ve\u00edculo utiliza a combina\u00e7\u00e3o testada e comprovada de trav\u00f5es de tambor traseiros e trav\u00f5es de disco dianteiros, esta \u00e9 ainda hoje perfeitamente adequada.\r\n\r\nEnt\u00e3o, A mudan\u00e7a de trav\u00f5es de tambor para trav\u00f5es de disco requer uma interven\u00e7\u00e3o maci\u00e7a no sistema de travagem de f\u00e1brica do ve\u00edculo. Como os inspectores n\u00e3o gostam nada disso durante a inspe\u00e7\u00e3o principal, deve sempre consultar um centro de inspe\u00e7\u00e3o antes de efetuar a convers\u00e3o. Al\u00e9m disso, a mudan\u00e7a representa um investimento grande e trabalhoso e n\u00e3o deve ser efectuada sem mais demoras. Se tiver esclarecido todos os pontos importantes e, mesmo assim, pretender efetuar uma altera\u00e7\u00e3o, ir\u00e1 certamente precisar de componentes que encaixem perfeitamente. Se tiver um ve\u00edculo com uma combina\u00e7\u00e3o de disco\/tambor, deve procurar o eixo traseiro de um modelo de ve\u00edculo id\u00eantico que j\u00e1 tenha trav\u00f5es de disco. Neste caso, pode efetuar a convers\u00e3o com componentes perfeitamente adequados. Em alternativa, pode encontrar algo adequado em toda a gama de componentes aprovados.\r\n\r\n&nbsp;\r\n\r\n<!-- \/wp:post-content -->","protected":false},"excerpt":{"rendered":"<p>A fiabilidade dos trav\u00f5es \u00e9 essencial para a seguran\u00e7a rodovi\u00e1ria dos ve\u00edculos a motor. A quest\u00e3o de saber se os trav\u00f5es de tambor ou os trav\u00f5es de disco s\u00e3o a melhor escolha para o tr\u00e1fego rodovi\u00e1rio tem sido objeto de um aceso debate durante anos. Os trav\u00f5es de tambor s\u00e3o a &#8220;base&#8221; da tecnologia de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":16564,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3294,641,422,421,361],"tags":[3575,3983,3340,3444,3338,3982,3984,3985],"class_list":["post-3721","post","type-post","status-publish","format-standard","has-post-thumbnail","category-automovel","category-carrossel","category-travao-de-disco","category-travao-de-tambor","category-travoes","tag-calcos-de-travao","tag-cuidados-com-o-carro","tag-disco-de-travao","tag-pastilhas-de-travao","tag-travoes","tag-travoes-de-carro","tag-travoes-de-disco","tag-travoes-de-tambor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco<\/title>\n<meta name=\"description\" content=\"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco - guia. A fiabilidade dos trav\u00f5es \u00e9 essencial para a seguran\u00e7a rodovi\u00e1ria.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/\" \/>\n<meta property=\"og:locale\" content=\"pt-PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco\" \/>\n<meta property=\"og:description\" content=\"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco - guia. A fiabilidade dos trav\u00f5es \u00e9 essencial para a seguran\u00e7a rodovi\u00e1ria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/\" \/>\n<meta property=\"og:site_name\" content=\"Motointegrator.pt Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-29T08:00:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T13:04:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.motointegrator.pt\/blog\/wp-content\/uploads\/sites\/17\/2024\/06\/travoes-de-tambor.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/conversao-de-travoes-de-tambor-em-travoes-de-disco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/conversao-de-travoes-de-tambor-em-travoes-de-disco\\\/\"},\"author\":{\"name\":\"Julian\",\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/#\\\/schema\\\/person\\\/ad08456e14b7e2d094198df618c274e7\"},\"headline\":\"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco &#8211; guia\",\"datePublished\":\"2024-06-29T08:00:36+00:00\",\"dateModified\":\"2025-11-25T13:04:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/conversao-de-travoes-de-tambor-em-travoes-de-disco\\\/\"},\"wordCount\":1545,\"image\":{\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/conversao-de-travoes-de-tambor-em-travoes-de-disco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2024\\\/06\\\/travoes-de-tambor.jpg\",\"keywords\":[\"cal\u00e7os de trav\u00e3o\",\"cuidados com o carro\",\"Disco de trav\u00e3o\",\"Pastilhas de trav\u00e3o\",\"Trav\u00f5es\",\"trav\u00f5es de carro\",\"trav\u00f5es de disco\",\"trav\u00f5es de tambor\"],\"articleSection\":[\"Autom\u00f3vel\",\"Carrossel\",\"Trav\u00e3o de disco\",\"Trav\u00e3o de tambor\",\"Trav\u00f5es\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/conversao-de-travoes-de-tambor-em-travoes-de-disco\\\/\",\"url\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/conversao-de-travoes-de-tambor-em-travoes-de-disco\\\/\",\"name\":\"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/conversao-de-travoes-de-tambor-em-travoes-de-disco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/conversao-de-travoes-de-tambor-em-travoes-de-disco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2024\\\/06\\\/travoes-de-tambor.jpg\",\"datePublished\":\"2024-06-29T08:00:36+00:00\",\"dateModified\":\"2025-11-25T13:04:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/#\\\/schema\\\/person\\\/ad08456e14b7e2d094198df618c274e7\"},\"description\":\"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco - guia. A fiabilidade dos trav\u00f5es \u00e9 essencial para a seguran\u00e7a rodovi\u00e1ria.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/conversao-de-travoes-de-tambor-em-travoes-de-disco\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/conversao-de-travoes-de-tambor-em-travoes-de-disco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/conversao-de-travoes-de-tambor-em-travoes-de-disco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2024\\\/06\\\/travoes-de-tambor.jpg\",\"contentUrl\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2024\\\/06\\\/travoes-de-tambor.jpg\",\"width\":500,\"height\":334,\"caption\":\"\u00a9Shutterstock \\\/ cowardlion\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/conversao-de-travoes-de-tambor-em-travoes-de-disco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco &#8211; guia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/\",\"name\":\"Motointegrator.pt Blog\",\"description\":\"O cantar dos pneus, o cheiro a gasolina, o esp\u00edrito de vit\u00f3ria, a experi\u00eancia dos carros desportivos de perto, a realiza\u00e7\u00e3o de sonhos de inf\u00e2ncia: eis o Motointegrator.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/#\\\/schema\\\/person\\\/ad08456e14b7e2d094198df618c274e7\",\"name\":\"Julian\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d62afc02463a844910f498015a9d043f9fa7dbe8aa6bc29bbdef401f1ff49de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d62afc02463a844910f498015a9d043f9fa7dbe8aa6bc29bbdef401f1ff49de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d62afc02463a844910f498015a9d043f9fa7dbe8aa6bc29bbdef401f1ff49de?s=96&d=mm&r=g\",\"caption\":\"Julian\"},\"url\":\"https:\\\/\\\/www.motointegrator.pt\\\/blog\\\/author\\\/motointegrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco","description":"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco - guia. A fiabilidade dos trav\u00f5es \u00e9 essencial para a seguran\u00e7a rodovi\u00e1ria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/","og_locale":"pt-PT","og_type":"article","og_title":"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco","og_description":"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco - guia. A fiabilidade dos trav\u00f5es \u00e9 essencial para a seguran\u00e7a rodovi\u00e1ria.","og_url":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/","og_site_name":"Motointegrator.pt Blog","article_published_time":"2024-06-29T08:00:36+00:00","article_modified_time":"2025-11-25T13:04:39+00:00","og_image":[{"width":500,"height":334,"url":"https:\/\/www.motointegrator.pt\/blog\/wp-content\/uploads\/sites\/17\/2024\/06\/travoes-de-tambor.jpg","type":"image\/jpeg"}],"author":"Julian","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julian","Tempo estimado de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/#article","isPartOf":{"@id":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/"},"author":{"name":"Julian","@id":"https:\/\/www.motointegrator.pt\/blog\/#\/schema\/person\/ad08456e14b7e2d094198df618c274e7"},"headline":"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco &#8211; guia","datePublished":"2024-06-29T08:00:36+00:00","dateModified":"2025-11-25T13:04:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/"},"wordCount":1545,"image":{"@id":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.motointegrator.pt\/blog\/wp-content\/uploads\/sites\/17\/2024\/06\/travoes-de-tambor.jpg","keywords":["cal\u00e7os de trav\u00e3o","cuidados com o carro","Disco de trav\u00e3o","Pastilhas de trav\u00e3o","Trav\u00f5es","trav\u00f5es de carro","trav\u00f5es de disco","trav\u00f5es de tambor"],"articleSection":["Autom\u00f3vel","Carrossel","Trav\u00e3o de disco","Trav\u00e3o de tambor","Trav\u00f5es"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/","url":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/","name":"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco","isPartOf":{"@id":"https:\/\/www.motointegrator.pt\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/#primaryimage"},"image":{"@id":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.motointegrator.pt\/blog\/wp-content\/uploads\/sites\/17\/2024\/06\/travoes-de-tambor.jpg","datePublished":"2024-06-29T08:00:36+00:00","dateModified":"2025-11-25T13:04:39+00:00","author":{"@id":"https:\/\/www.motointegrator.pt\/blog\/#\/schema\/person\/ad08456e14b7e2d094198df618c274e7"},"description":"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco - guia. A fiabilidade dos trav\u00f5es \u00e9 essencial para a seguran\u00e7a rodovi\u00e1ria.","breadcrumb":{"@id":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/#primaryimage","url":"https:\/\/www.motointegrator.pt\/blog\/wp-content\/uploads\/sites\/17\/2024\/06\/travoes-de-tambor.jpg","contentUrl":"https:\/\/www.motointegrator.pt\/blog\/wp-content\/uploads\/sites\/17\/2024\/06\/travoes-de-tambor.jpg","width":500,"height":334,"caption":"\u00a9Shutterstock \/ cowardlion"},{"@type":"BreadcrumbList","@id":"https:\/\/www.motointegrator.pt\/blog\/conversao-de-travoes-de-tambor-em-travoes-de-disco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.motointegrator.pt\/blog\/"},{"@type":"ListItem","position":2,"name":"Convers\u00e3o de trav\u00f5es de tambor em trav\u00f5es de disco &#8211; guia"}]},{"@type":"WebSite","@id":"https:\/\/www.motointegrator.pt\/blog\/#website","url":"https:\/\/www.motointegrator.pt\/blog\/","name":"Motointegrator.pt Blog","description":"O cantar dos pneus, o cheiro a gasolina, o esp\u00edrito de vit\u00f3ria, a experi\u00eancia dos carros desportivos de perto, a realiza\u00e7\u00e3o de sonhos de inf\u00e2ncia: eis o Motointegrator.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.motointegrator.pt\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.motointegrator.pt\/blog\/#\/schema\/person\/ad08456e14b7e2d094198df618c274e7","name":"Julian","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/2d62afc02463a844910f498015a9d043f9fa7dbe8aa6bc29bbdef401f1ff49de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d62afc02463a844910f498015a9d043f9fa7dbe8aa6bc29bbdef401f1ff49de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d62afc02463a844910f498015a9d043f9fa7dbe8aa6bc29bbdef401f1ff49de?s=96&d=mm&r=g","caption":"Julian"},"url":"https:\/\/www.motointegrator.pt\/blog\/author\/motointegrator\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.motointegrator.pt\/blog\/wp-json\/wp\/v2\/posts\/3721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.motointegrator.pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.motointegrator.pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.motointegrator.pt\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.motointegrator.pt\/blog\/wp-json\/wp\/v2\/comments?post=3721"}],"version-history":[{"count":14,"href":"https:\/\/www.motointegrator.pt\/blog\/wp-json\/wp\/v2\/posts\/3721\/revisions"}],"predecessor-version":[{"id":32956,"href":"https:\/\/www.motointegrator.pt\/blog\/wp-json\/wp\/v2\/posts\/3721\/revisions\/32956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.motointegrator.pt\/blog\/wp-json\/wp\/v2\/media\/16564"}],"wp:attachment":[{"href":"https:\/\/www.motointegrator.pt\/blog\/wp-json\/wp\/v2\/media?parent=3721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.motointegrator.pt\/blog\/wp-json\/wp\/v2\/categories?post=3721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.motointegrator.pt\/blog\/wp-json\/wp\/v2\/tags?post=3721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}